{"id":5258,"date":"2017-05-18T13:06:42","date_gmt":"2017-05-18T11:06:42","guid":{"rendered":"http:\/\/cultura.umh.es\/?p=5258"},"modified":"2023-09-07T12:54:30","modified_gmt":"2023-09-07T10:54:30","slug":"concert-fi-de-curs-joumh","status":"publish","type":"post","link":"https:\/\/cultura.umh.es\/es\/2017\/05\/18\/concert-fi-de-curs-joumh\/","title":{"rendered":"CONCIERTO FIN DE CURSO JOUMH"},"content":{"rendered":"<p><a href=\"https:\/\/cultura.umh.es\/files\/2017\/05\/Cartel_ConciertoJOUMHOrihuelaVALweb.jpg\"><img loading=\"lazy\" class=\" wp-image-5260 alignleft\" src=\"https:\/\/cultura.umh.es\/files\/2017\/05\/Cartel_ConciertoJOUMHOrihuelaVALweb-212x300.jpg\" alt=\"Cartel_ConciertoJOUMHOrihuelaVALweb\" width=\"273\" height=\"386\" srcset=\"https:\/\/cultura.umh.es\/files\/2017\/05\/Cartel_ConciertoJOUMHOrihuelaVALweb-212x300.jpg 212w, https:\/\/cultura.umh.es\/files\/2017\/05\/Cartel_ConciertoJOUMHOrihuelaVALweb-768x1086.jpg 768w, https:\/\/cultura.umh.es\/files\/2017\/05\/Cartel_ConciertoJOUMHOrihuelaVALweb-724x1024.jpg 724w, https:\/\/cultura.umh.es\/files\/2017\/05\/Cartel_ConciertoJOUMHOrihuelaVALweb.jpg 1240w\" sizes=\"(max-width: 273px) 100vw, 273px\" \/><\/a><\/p>\n<p><strong><span style=\"text-decoration: underline\">Concierto JOUMH\u00a0<\/span><\/strong><\/p>\n<p><u>Fecha<\/u>: 2 de junio del 2017.<\/p>\n<p><span style=\"text-decoration: underline\">Hora<\/span>: 18.30 h.<\/p>\n<p><span style=\"text-decoration: underline\">Entrada<\/span>: Libre hasta completar el aforo.<\/p>\n<p><span style=\"text-decoration: underline\">Director<\/span>: Paco serra.<\/p>\n<p><span style=\"text-decoration: underline\">Luga<\/span>r: Teatro circo Atanasio D\u00ede Marin de Orihuela.<\/p>","protected":false},"excerpt":{"rendered":"<p>Concierto JOUMH\u00a0<br \/>\nFecha: 2 de junio del 2017.<br \/>\nHora: 18.30 h.<br \/>\nEntrada: Libre hasta completar el aforo.<br \/>\nDirector: Paco serra.<br \/>\nLugar: Teatro circo Atanasio D\u00ede Marin de Orihuela.<\/p>\n","protected":false},"author":3617,"featured_media":5259,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_links_to":"","_links_to_target":""},"categories":[55515],"tags":[44426],"_links":{"self":[{"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/posts\/5258"}],"collection":[{"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/users\/3617"}],"replies":[{"embeddable":true,"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/comments?post=5258"}],"version-history":[{"count":0,"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/posts\/5258\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/media\/5259"}],"wp:attachment":[{"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/media?parent=5258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/categories?post=5258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cultura.umh.es\/es\/wp-json\/wp\/v2\/tags?post=5258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}